{"id":15953,"date":"2026-07-15T17:00:20","date_gmt":"2026-07-15T15:00:20","guid":{"rendered":"https:\/\/deep-space-astronomy.ch\/?post_type=product&#038;p=15953"},"modified":"2026-07-15T18:00:34","modified_gmt":"2026-07-15T16:00:34","slug":"celestron-omni-plossl-32mm","status":"publish","type":"product","link":"https:\/\/deep-space-astronomy.ch\/de\/produkt\/celestron-omni-plossl-32mm\/","title":{"rendered":"Celestron Omni Pl\u00f6ssl 32 mm"},"content":{"rendered":"<p>Les oculaires Omni Pl\u00f6ssl b\u00e9n\u00e9ficient d\u2019une conception optique de qualit\u00e9 \u00e0 4 \u00e9l\u00e9ments, propos\u00e9e \u00e0 un prix particuli\u00e8rement accessible.<\/p>\n<ul>\n<li>Les bonnettes en caoutchouc offrent un meilleur confort d\u2019observation et contribuent \u00e0 augmenter le contraste. Elles peuvent \u00eatre laiss\u00e9es relev\u00e9es ou rabattues pour les porteurs de lunettes.<\/li>\n<li>Le corps \u00e9l\u00e9gant en aluminium mat et les bords de lentilles noircis r\u00e9duisent efficacement les r\u00e9flexions internes.<\/li>\n<li>Le coulant de 1,25&Prime; est filet\u00e9 afin de permettre l\u2019utilisation de filtres astronomiques compatibles.<\/li>\n<\/ul>\n<h2>Technische Daten<\/h2>\n<table>\n<tbody>\n<tr>\n<th>Taille du coulant<\/th>\n<td>1,25&Prime; (32 mm)<\/td>\n<\/tr>\n<tr>\n<th>Brennweite<\/th>\n<td>32 mm<\/td>\n<\/tr>\n<tr>\n<th>Type d\u2019oculaire<\/th>\n<td>Pl\u00f6ssl<\/td>\n<\/tr>\n<tr>\n<th>Diam\u00e8tre du diaphragme de champ<\/th>\n<td>27,5 mm<\/td>\n<\/tr>\n<tr>\n<th>Scheinbares Feld<\/th>\n<td>48\u00b0<\/td>\n<\/tr>\n<tr>\n<th>Nombre d\u2019\u00e9l\u00e9ments optiques<\/th>\n<td>4<\/td>\n<\/tr>\n<tr>\n<th>Nombre de groupes optiques<\/th>\n<td>2<\/td>\n<\/tr>\n<tr>\n<th>Optische Verarbeitung<\/th>\n<td>Mehrschichtig<\/td>\n<\/tr>\n<tr>\n<th>D\u00e9gagement oculaire<\/th>\n<td>22 mm<\/td>\n<\/tr>\n<tr>\n<th>Parfocal<\/th>\n<td>Nicht<\/td>\n<\/tr>\n<tr>\n<th>Gewinde f\u00fcr Filter<\/th>\n<td>Ja<\/td>\n<\/tr>\n<tr>\n<th>Bonnette<\/th>\n<td>Oui, rabattable<\/td>\n<\/tr>\n<tr>\n<th>Mat\u00e9riau du corps<\/th>\n<td>Aluminium<\/td>\n<\/tr>\n<tr>\n<th>\u00c9tanche<\/th>\n<td>Nicht<\/td>\n<\/tr>\n<tr>\n<th>Abmessungen<\/th>\n<td>83,6 \u00d7 40 \u00d7 40 mm<\/td>\n<\/tr>\n<tr>\n<th>Gewicht<\/th>\n<td>112,5 g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Les oculaires Omni Pl\u00f6ssl b\u00e9n\u00e9ficient d\u2019une conception optique de qualit\u00e9 \u00e0 4 \u00e9l\u00e9ments, propos\u00e9e \u00e0 un prix particuli\u00e8rement accessible. Les bonnettes en caoutchouc offrent un meilleur confort d\u2019observation et contribuent \u00e0 augmenter le contraste. Elles peuvent \u00eatre laiss\u00e9es relev\u00e9es ou rabattues pour les porteurs de lunettes. Le corps \u00e9l\u00e9gant en aluminium mat et les bords [&hellip;]<\/p>\n","protected":false},"featured_media":15964,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[413],"product_cat":[695],"product_tag":[],"class_list":["post-15953","product","type-product","status-publish","has-post-thumbnail","product_brand-celestron","product_cat-oculaires-et-smart-oculaires","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/product\/15953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/comments?post=15953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/media\/15964"}],"wp:attachment":[{"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/media?parent=15953"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/product_brand?post=15953"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/product_cat?post=15953"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deep-space-astronomy.ch\/de\/wp-json\/wp\/v2\/product_tag?post=15953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}